{"id":14121,"date":"2021-02-19T06:54:46","date_gmt":"2021-02-19T13:54:46","guid":{"rendered":"https:\/\/www.nevadaregistry.org\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/"},"modified":"2025-05-02T14:29:26","modified_gmt":"2025-05-02T21:29:26","slug":"centro-de-llamadas-para-la-vacuna-covid-19","status":"publish","type":"post","link":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/","title":{"rendered":"Centro de llamadas para la vacuna COVID-19"},"content":{"rendered":"<p><em><strong>Actualizado en mayo de 2023<\/strong><\/em><\/p>\n<p>El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s) ha lanzado un centro de llamadas de vacunaci\u00f3n para responder preguntas y asistir a las personas que necesitan ayuda para programar una cita. A trav\u00e9s del centro de llamadas, los residentes de Nevada podr\u00e1n acceder a actualizaciones e informaci\u00f3n espec\u00edficas de cada condado a medida que m\u00e1s habitantes de Nevada sean elegibles para recibir la vacuna contra el COVID-19. <\/p>\n<p><strong>Nota: El centro de llamadas estatal de COVID de Nevada no ha cesado sus servicios. Las personas que busquen informaci\u00f3n sobre COVID ahora deben comunicarse con Nevada 2-1-1 (en lugar del centro de llamadas).  <\/strong><\/p>\n<p>Para aquellos con acceso a internet, el DHHS contin\u00faa alentando a los residentes a buscar en l\u00ednea la informaci\u00f3n m\u00e1s reciente sobre vacunaciones a trav\u00e9s de <a href=\"https:\/\/www.immunizenevada.org\/nv-covid-fighter\" data-auth=\"NotApplicable\">NVCOVIDFighter.org.<\/a> <\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n, orientaci\u00f3n y recursos sobre la respuesta de Nevada a la COVID-19, visite <a href=\"https:\/\/nvhealthresponse.nv.gov\/\" data-auth=\"NotApplicable\">https:\/\/nvhealthresponse.nv.gov\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actualizado en mayo de 2023 El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s)&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-14121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relacionado-con-la-salud-covid-19"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro de llamadas para la vacuna COVID-19 - The Nevada Registry<\/title>\n<meta name=\"description\" content=\"Actualizado en mayo de 2023 El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s) ha lanzado un centro de llamadas de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro de llamadas para la vacuna COVID-19 - The Nevada Registry\" \/>\n<meta property=\"og:description\" content=\"Actualizado en mayo de 2023 El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s) ha lanzado un centro de llamadas de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"The Nevada Registry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nevadaregistry\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T13:54:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T21:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/01\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2266\" \/>\n\t<meta property=\"og:image:height\" content=\"1322\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shelly Nye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shelly Nye\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/\"},\"author\":{\"name\":\"Shelly Nye\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\"},\"headline\":\"Centro de llamadas para la vacuna COVID-19\",\"datePublished\":\"2021-02-19T13:54:46+00:00\",\"dateModified\":\"2025-05-02T21:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/\"},\"wordCount\":184,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg\",\"articleSection\":[\"Relacionado con la salud\\\/COVID-19\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/\",\"name\":\"Centro de llamadas para la vacuna COVID-19 - The Nevada Registry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg\",\"datePublished\":\"2021-02-19T13:54:46+00:00\",\"dateModified\":\"2025-05-02T21:29:26+00:00\",\"description\":\"Actualizado en mayo de 2023 El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s) ha lanzado un centro de llamadas de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg\",\"width\":\"2266\",\"height\":\"1322\",\"caption\":\"Row Covid-19 or Coronavirus vaccine flasks on white background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/centro-de-llamadas-para-la-vacuna-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/pagina-principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro de llamadas para la vacuna COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"name\":\"The Nevada Registry\",\"description\":\"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\",\"name\":\"El Nevada Registry\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"width\":\"900\",\"height\":\"562\",\"caption\":\"El Nevada Registry\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nevadaregistry\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\",\"name\":\"Shelly Nye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"caption\":\"Shelly Nye\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro de llamadas para la vacuna COVID-19 - The Nevada Registry","description":"Actualizado en mayo de 2023 El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s) ha lanzado un centro de llamadas de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Centro de llamadas para la vacuna COVID-19 - The Nevada Registry","og_description":"Actualizado en mayo de 2023 El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s) ha lanzado un centro de llamadas de","og_url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/","og_site_name":"The Nevada Registry","article_publisher":"https:\/\/www.facebook.com\/nevadaregistry","article_published_time":"2021-02-19T13:54:46+00:00","article_modified_time":"2025-05-02T21:29:26+00:00","og_image":[{"width":2266,"height":1322,"url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/01\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg","type":"image\/jpeg"}],"author":"Shelly Nye","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Shelly Nye","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/"},"author":{"name":"Shelly Nye","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985"},"headline":"Centro de llamadas para la vacuna COVID-19","datePublished":"2021-02-19T13:54:46+00:00","dateModified":"2025-05-02T21:29:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/"},"wordCount":184,"publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/01\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg","articleSection":["Relacionado con la salud\/COVID-19"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/","url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/","name":"Centro de llamadas para la vacuna COVID-19 - The Nevada Registry","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/01\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg","datePublished":"2021-02-19T13:54:46+00:00","dateModified":"2025-05-02T21:29:26+00:00","description":"Actualizado en mayo de 2023 El Departamento de Salud y Servicios Humanos de Nevada (DHHS, por sus siglas en ingl\u00e9s) ha lanzado un centro de llamadas de","breadcrumb":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/#primaryimage","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/01\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/01\/Close-up-of-bottles-of-COVID-19-vaccine-1288583851_2270x1324.jpeg","width":"2266","height":"1322","caption":"Row Covid-19 or Coronavirus vaccine flasks on white background"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/centro-de-llamadas-para-la-vacuna-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nevadaregistry.org\/es\/pagina-principal\/"},{"@type":"ListItem","position":2,"name":"Centro de llamadas para la vacuna COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.nevadaregistry.org\/es\/#website","url":"https:\/\/www.nevadaregistry.org\/es\/","name":"The Nevada Registry","description":"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.","publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nevadaregistry.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nevadaregistry.org\/es\/#organization","name":"El Nevada Registry","url":"https:\/\/www.nevadaregistry.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","width":"900","height":"562","caption":"El Nevada Registry"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nevadaregistry"]},{"@type":"Person","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985","name":"Shelly Nye","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","caption":"Shelly Nye"}}]}},"_links":{"self":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/comments?post=14121"}],"version-history":[{"count":1,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14121\/revisions"}],"predecessor-version":[{"id":14122,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14121\/revisions\/14122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media\/11679"}],"wp:attachment":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media?parent=14121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/categories?post=14121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/tags?post=14121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}