{"id":14243,"date":"2020-04-09T09:14:36","date_gmt":"2020-04-09T16:14:36","guid":{"rendered":"https:\/\/www.nevadaregistry.org\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/"},"modified":"2025-05-02T14:31:53","modified_gmt":"2025-05-02T21:31:53","slug":"ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil","status":"publish","type":"post","link":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/","title":{"rendered":"Ayudando con las necesidades de los proveedores de cuidado infantil"},"content":{"rendered":"<div id=\"hidbg\">\n<div id=\"owrap\">\n<div id=\"wrap\">\n<div id=\"content\">\n<p>El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a todos los proveedores de cuidado infantil que respondieron a su encuesta. Esto les ha ayudado enormemente a comprender lo que est\u00e1 sucediendo en primera l\u00ednea. \u00a1Su voz est\u00e1 siendo escuchada!  <\/p>\n<p>Para brindarles m\u00e1s apoyo, han redactado una carta (v\u00e9ase el enlace a continuaci\u00f3n) que aborda las necesidades de los proveedores de cuidado infantil (tales como efectivo, suministros y alimentos) y algunas de las opciones disponibles para ayudar (como estipendios de emergencia y pr\u00e9stamos).<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n, recursos y orientaci\u00f3n sobre la respuesta de Nevada ante el COVID-19, visite <a href=\"https:\/\/nvhealthresponse.nv.gov\/\">https:\/\/nvhealthresponse.nv.gov\/<\/a>.<\/p>\n<p><a href=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/Letter-to-Providers-Financial-Help.pdf\">Carta a los proveedores sobre ayuda financiera<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[55,53],"tags":[],"class_list":["post-14243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-la-industria","category-relacionado-con-la-salud-covid-19"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ayudando con las necesidades de los proveedores de cuidado infantil - The Nevada Registry<\/title>\n<meta name=\"description\" content=\"El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a todos los proveedores de cuidado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ayudando con las necesidades de los proveedores de cuidado infantil - The Nevada Registry\" \/>\n<meta property=\"og:description\" content=\"El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a todos los proveedores de cuidado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/\" \/>\n<meta property=\"og:site_name\" content=\"The Nevada Registry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nevadaregistry\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T16:14:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T21:31:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2129\" \/>\n\t<meta property=\"og:image:height\" content=\"1408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shelly Nye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shelly Nye\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/\"},\"author\":{\"name\":\"Shelly Nye\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\"},\"headline\":\"Ayudando con las necesidades de los proveedores de cuidado infantil\",\"datePublished\":\"2020-04-09T16:14:36+00:00\",\"dateModified\":\"2025-05-02T21:31:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/\"},\"wordCount\":140,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg\",\"articleSection\":[\"Noticias de la Industria\",\"Relacionado con la salud\\\/COVID-19\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/\",\"name\":\"Ayudando con las necesidades de los proveedores de cuidado infantil - The Nevada Registry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg\",\"datePublished\":\"2020-04-09T16:14:36+00:00\",\"dateModified\":\"2025-05-02T21:31:53+00:00\",\"description\":\"El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a todos los proveedores de cuidado\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg\",\"width\":\"2129\",\"height\":\"1408\",\"caption\":\"COVID 19 pandemic - roadsign message\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/pagina-principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayudando con las necesidades de los proveedores de cuidado infantil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"name\":\"The Nevada Registry\",\"description\":\"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\",\"name\":\"El Nevada Registry\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"width\":\"900\",\"height\":\"562\",\"caption\":\"El Nevada Registry\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nevadaregistry\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\",\"name\":\"Shelly Nye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"caption\":\"Shelly Nye\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ayudando con las necesidades de los proveedores de cuidado infantil - The Nevada Registry","description":"El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a todos los proveedores de cuidado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/","og_locale":"es_ES","og_type":"article","og_title":"Ayudando con las necesidades de los proveedores de cuidado infantil - The Nevada Registry","og_description":"El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a todos los proveedores de cuidado","og_url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/","og_site_name":"The Nevada Registry","article_publisher":"https:\/\/www.facebook.com\/nevadaregistry","article_published_time":"2020-04-09T16:14:36+00:00","article_modified_time":"2025-05-02T21:31:53+00:00","og_image":[{"width":2129,"height":1408,"url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg","type":"image\/jpeg"}],"author":"Shelly Nye","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Shelly Nye","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/#article","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/"},"author":{"name":"Shelly Nye","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985"},"headline":"Ayudando con las necesidades de los proveedores de cuidado infantil","datePublished":"2020-04-09T16:14:36+00:00","dateModified":"2025-05-02T21:31:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/"},"wordCount":140,"publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg","articleSection":["Noticias de la Industria","Relacionado con la salud\/COVID-19"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/","url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/","name":"Ayudando con las necesidades de los proveedores de cuidado infantil - The Nevada Registry","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/#primaryimage"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg","datePublished":"2020-04-09T16:14:36+00:00","dateModified":"2025-05-02T21:31:53+00:00","description":"El Programa de Cuidado y Desarrollo Infantil de Nevada (CCDP, por sus siglas en ingl\u00e9s) env\u00eda un gran agradecimiento a todos los proveedores de cuidado","breadcrumb":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/#primaryimage","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/COVID-19-pandemic-roadsign-message-1211154635_2132x1410.jpeg","width":"2129","height":"1408","caption":"COVID 19 pandemic - roadsign message"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/ayudando-con-las-necesidades-de-los-proveedores-de-cuidado-infantil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nevadaregistry.org\/es\/pagina-principal\/"},{"@type":"ListItem","position":2,"name":"Ayudando con las necesidades de los proveedores de cuidado infantil"}]},{"@type":"WebSite","@id":"https:\/\/www.nevadaregistry.org\/es\/#website","url":"https:\/\/www.nevadaregistry.org\/es\/","name":"The Nevada Registry","description":"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.","publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nevadaregistry.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nevadaregistry.org\/es\/#organization","name":"El Nevada Registry","url":"https:\/\/www.nevadaregistry.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","width":"900","height":"562","caption":"El Nevada Registry"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nevadaregistry"]},{"@type":"Person","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985","name":"Shelly Nye","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","caption":"Shelly Nye"}}]}},"_links":{"self":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/comments?post=14243"}],"version-history":[{"count":1,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14243\/revisions"}],"predecessor-version":[{"id":14244,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14243\/revisions\/14244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media\/11637"}],"wp:attachment":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media?parent=14243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/categories?post=14243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/tags?post=14243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}