{"id":14689,"date":"2020-01-24T14:50:55","date_gmt":"2020-01-24T21:50:55","guid":{"rendered":"https:\/\/www.nevadaregistry.org\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/"},"modified":"2025-05-02T14:44:10","modified_gmt":"2025-05-02T21:44:10","slug":"estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3","status":"publish","type":"post","link":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/","title":{"rendered":"Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3"},"content":{"rendered":"<div id=\"hidbg\">\n<div id=\"owrap\">\n<div id=\"wrap\">\n<div id=\"content\">\n<p>Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos PRESENTADORES DE CONFERENCIAS que se registraron esta semana. Un total de 134 formadores han renovado\/sido aprobados desde el 6 de enero de 2020. En combinaci\u00f3n con los 66 formadores registrados, actualmente hay 200 formadores activos disponibles para impartir formaci\u00f3n en Nevada. Asimismo, se han aprobado 370 sesiones de formaci\u00f3n.   <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-14689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sistema-de-aprobacion-de-formacion-informacion-para-formadores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3 - The Nevada Registry<\/title>\n<meta name=\"description\" content=\"Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos PRESENTADORES DE\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3 - The Nevada Registry\" \/>\n<meta property=\"og:description\" content=\"Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos PRESENTADORES DE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/\" \/>\n<meta property=\"og:site_name\" content=\"The Nevada Registry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nevadaregistry\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-24T21:50:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T21:44:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/07\/iStock_71328503_LARGE-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shelly Nye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shelly Nye\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/\"},\"author\":{\"name\":\"Shelly Nye\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\"},\"headline\":\"Estado de Renovaci\u00f3n\\\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3\",\"datePublished\":\"2020-01-24T21:50:55+00:00\",\"dateModified\":\"2025-05-02T21:44:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/\"},\"wordCount\":81,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/iStock_71328503_LARGE-scaled.jpg\",\"articleSection\":[\"Sistema de Aprobaci\u00f3n de Formaci\u00f3n\\\/Informaci\u00f3n para Formadores\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/\",\"name\":\"Estado de Renovaci\u00f3n\\\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3 - The Nevada Registry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/iStock_71328503_LARGE-scaled.jpg\",\"datePublished\":\"2020-01-24T21:50:55+00:00\",\"dateModified\":\"2025-05-02T21:44:10+00:00\",\"description\":\"Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos PRESENTADORES DE\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/iStock_71328503_LARGE-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/iStock_71328503_LARGE-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Little girl with umbrella in autumn\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/pagina-principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estado de Renovaci\u00f3n\\\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"name\":\"The Nevada Registry\",\"description\":\"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\",\"name\":\"El Nevada Registry\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"width\":\"900\",\"height\":\"562\",\"caption\":\"El Nevada Registry\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nevadaregistry\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\",\"name\":\"Shelly Nye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"caption\":\"Shelly Nye\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3 - The Nevada Registry","description":"Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos PRESENTADORES DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/","og_locale":"es_ES","og_type":"article","og_title":"Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3 - The Nevada Registry","og_description":"Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos PRESENTADORES DE","og_url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/","og_site_name":"The Nevada Registry","article_publisher":"https:\/\/www.facebook.com\/nevadaregistry","article_published_time":"2020-01-24T21:50:55+00:00","article_modified_time":"2025-05-02T21:44:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/07\/iStock_71328503_LARGE-scaled.jpg","type":"image\/jpeg"}],"author":"Shelly Nye","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Shelly Nye"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/#article","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/"},"author":{"name":"Shelly Nye","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985"},"headline":"Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3","datePublished":"2020-01-24T21:50:55+00:00","dateModified":"2025-05-02T21:44:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/"},"wordCount":81,"publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/07\/iStock_71328503_LARGE-scaled.jpg","articleSection":["Sistema de Aprobaci\u00f3n de Formaci\u00f3n\/Informaci\u00f3n para Formadores"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/","url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/","name":"Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3 - The Nevada Registry","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/#primaryimage"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/07\/iStock_71328503_LARGE-scaled.jpg","datePublished":"2020-01-24T21:50:55+00:00","dateModified":"2025-05-02T21:44:10+00:00","description":"Felicitaciones a los siete formadores RETORNANTES que fueron aprobados esta semana, as\u00ed como a los tres PRESENTADORES PATROCINADOS y dos PRESENTADORES DE","breadcrumb":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/#primaryimage","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/07\/iStock_71328503_LARGE-scaled.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/07\/iStock_71328503_LARGE-scaled.jpg","width":2560,"height":1707,"caption":"Little girl with umbrella in autumn"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/estado-de-renovacion-aprobacion-de-formadores-de-2020-a-partir-de-la-semana-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nevadaregistry.org\/es\/pagina-principal\/"},{"@type":"ListItem","position":2,"name":"Estado de Renovaci\u00f3n\/Aprobaci\u00f3n de Formadores de 2020 a partir de la Semana 3"}]},{"@type":"WebSite","@id":"https:\/\/www.nevadaregistry.org\/es\/#website","url":"https:\/\/www.nevadaregistry.org\/es\/","name":"The Nevada Registry","description":"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.","publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nevadaregistry.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nevadaregistry.org\/es\/#organization","name":"El Nevada Registry","url":"https:\/\/www.nevadaregistry.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","width":"900","height":"562","caption":"El Nevada Registry"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nevadaregistry"]},{"@type":"Person","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985","name":"Shelly Nye","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","caption":"Shelly Nye"}}]}},"_links":{"self":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/comments?post=14689"}],"version-history":[{"count":1,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14689\/revisions"}],"predecessor-version":[{"id":14690,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14689\/revisions\/14690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media\/11304"}],"wp:attachment":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media?parent=14689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/categories?post=14689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/tags?post=14689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}