{"id":14767,"date":"2021-06-23T11:25:11","date_gmt":"2021-06-23T18:25:11","guid":{"rendered":"https:\/\/www.nevadaregistry.org\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/"},"modified":"2025-05-02T14:56:34","modified_gmt":"2025-05-02T21:56:34","slug":"nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades","status":"publish","type":"post","link":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/","title":{"rendered":"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades"},"content":{"rendered":"<div>\n<p>La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de Alabama en Huntsville est\u00e1n llevando a cabo <b>un estudio para comprender mejor las experiencias de las familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades al tomar decisiones sobre el cuidado infantil para su familia, incluyendo el impacto de COVID en sus necesidades de cuidado infantil.<\/b><\/p>\n<p><a href=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/06\/Recruitment-Flyer.pdf\">Enlace al folleto<\/a><\/p>\n<\/div>\n<div>\n<p>Se le invita a responder una serie de preguntas sobre sus experiencias al decidir sobre el cuidado infantil, sus experiencias con programas de cuidado infantil y sus perspectivas sobre la inclusi\u00f3n de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades en entornos de cuidado infantil. Esta encuesta en l\u00ednea tomar\u00e1 aproximadamente 10-20 minutos para completarse. Los hallazgos de este estudio proporcionar\u00e1n informaci\u00f3n sobre las necesidades de las familias relacionadas con el cuidado infantil que pueden guiar futuras investigaciones, pol\u00edticas y programaci\u00f3n. Este estudio ha sido revisado y aprobado por la Junta de Revisi\u00f3n Institucional de la Universidad de Nevada, Las Vegas.   <\/p>\n<\/div>\n<div><\/div>\n<div>\n<p>Para obtener m\u00e1s informaci\u00f3n o comenzar la encuesta, haga clic en el siguiente enlace:<\/p>\n<p><a href=\"https:\/\/urldefense.com\/v3\/__https:\/unlv.co1.qualtrics.com\/jfe\/form\/SV_5bi8HxC7CzomBBc__;!!N0rdg9Wr!9GXiiCYNCcut-DpxFLxPMnOcl39kJBro3XD2INGO2RbQpj6bxElZZKjluy1ynSM%24\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">Encuesta<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[52],"tags":[],"class_list":["post-14767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-defensa-politicas-publicas-y-legislacion-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades - The Nevada Registry<\/title>\n<meta name=\"description\" content=\"La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de Alabama en Huntsville est\u00e1n llevando a cabo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades - The Nevada Registry\" \/>\n<meta property=\"og:description\" content=\"La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de Alabama en Huntsville est\u00e1n llevando a cabo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/\" \/>\n<meta property=\"og:site_name\" content=\"The Nevada Registry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nevadaregistry\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T18:25:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T21:56:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/06\/shutterstock_469060391.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shelly Nye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shelly Nye\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/\"},\"author\":{\"name\":\"Shelly Nye\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\"},\"headline\":\"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades\",\"datePublished\":\"2021-06-23T18:25:11+00:00\",\"dateModified\":\"2025-05-02T21:56:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/\"},\"wordCount\":212,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/shutterstock_469060391.jpg\",\"articleSection\":[\"Defensa, Pol\u00edticas P\u00fablicas y Legislaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/\",\"name\":\"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades - The Nevada Registry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/shutterstock_469060391.jpg\",\"datePublished\":\"2021-06-23T18:25:11+00:00\",\"dateModified\":\"2025-05-02T21:56:34+00:00\",\"description\":\"La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de Alabama en Huntsville est\u00e1n llevando a cabo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/shutterstock_469060391.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/shutterstock_469060391.jpg\",\"width\":\"2000\",\"height\":\"2000\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/pagina-principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"name\":\"The Nevada Registry\",\"description\":\"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\",\"name\":\"El Nevada Registry\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"width\":\"900\",\"height\":\"562\",\"caption\":\"El Nevada Registry\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nevadaregistry\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\",\"name\":\"Shelly Nye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"caption\":\"Shelly Nye\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades - The Nevada Registry","description":"La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de Alabama en Huntsville est\u00e1n llevando a cabo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades - The Nevada Registry","og_description":"La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de Alabama en Huntsville est\u00e1n llevando a cabo","og_url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/","og_site_name":"The Nevada Registry","article_publisher":"https:\/\/www.facebook.com\/nevadaregistry","article_published_time":"2021-06-23T18:25:11+00:00","article_modified_time":"2025-05-02T21:56:34+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/06\/shutterstock_469060391.jpg","type":"image\/jpeg"}],"author":"Shelly Nye","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Shelly Nye","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/#article","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/"},"author":{"name":"Shelly Nye","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985"},"headline":"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades","datePublished":"2021-06-23T18:25:11+00:00","dateModified":"2025-05-02T21:56:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/"},"wordCount":212,"publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/06\/shutterstock_469060391.jpg","articleSection":["Defensa, Pol\u00edticas P\u00fablicas y Legislaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/","url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/","name":"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades - The Nevada Registry","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/#primaryimage"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/06\/shutterstock_469060391.jpg","datePublished":"2021-06-23T18:25:11+00:00","dateModified":"2025-05-02T21:56:34+00:00","description":"La Dra. Jenna Weglarz-Ward de la Universidad de Nevada, Las Vegas y la Dra. Kimberly Hile de la Universidad de Alabama en Huntsville est\u00e1n llevando a cabo","breadcrumb":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/#primaryimage","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/06\/shutterstock_469060391.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2021\/06\/shutterstock_469060391.jpg","width":"2000","height":"2000"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/nueva-encuesta-para-familias-de-bebes-y-ninos-pequenos-con-discapacidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nevadaregistry.org\/es\/pagina-principal\/"},{"@type":"ListItem","position":2,"name":"Nueva encuesta para familias de beb\u00e9s y ni\u00f1os peque\u00f1os con discapacidades"}]},{"@type":"WebSite","@id":"https:\/\/www.nevadaregistry.org\/es\/#website","url":"https:\/\/www.nevadaregistry.org\/es\/","name":"The Nevada Registry","description":"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.","publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nevadaregistry.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nevadaregistry.org\/es\/#organization","name":"El Nevada Registry","url":"https:\/\/www.nevadaregistry.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","width":"900","height":"562","caption":"El Nevada Registry"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nevadaregistry"]},{"@type":"Person","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985","name":"Shelly Nye","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","caption":"Shelly Nye"}}]}},"_links":{"self":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/comments?post=14767"}],"version-history":[{"count":1,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14767\/revisions"}],"predecessor-version":[{"id":14768,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/14767\/revisions\/14768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media\/11749"}],"wp:attachment":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media?parent=14767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/categories?post=14767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/tags?post=14767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}