{"id":18576,"date":"2026-05-21T14:37:40","date_gmt":"2026-05-21T21:37:40","guid":{"rendered":"https:\/\/www.nevadaregistry.org\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/"},"modified":"2026-05-21T14:38:11","modified_gmt":"2026-05-21T21:38:11","slug":"tasas-de-reembolso-a-tiempo-completo","status":"publish","type":"post","link":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/","title":{"rendered":"Tasas de reembolso a tiempo completo"},"content":{"rendered":"<h6><em>Un mensaje de DSS &#8211; Programa de Cuidado y Desarrollo Infantil:<\/em><\/h6>\n<p>A partir del 1 de junio de 2026, cuando un ni\u00f1o asista durante quince (15) minutos o m\u00e1s en un d\u00eda permitido en un proveedor de cuidado infantil con licencia, incluyendo Centros de Cuidado Infantil, Hogares de Cuidado Infantil Familiar en Grupo y Hogares de Cuidado Infantil Familiar, el proveedor ser\u00e1 reembolsado a una tarifa de tiempo completo por ese d\u00eda. Para ser reembolsado, la hoja de horas debe seguir incluyendo las horas de entrada y salida de cada d\u00eda que el ni\u00f1o estuvo presente en el proveedor. <\/p>\n<p>Para m\u00e1s informaci\u00f3n, revise este Memor\u00e1ndum, \u201c<a href=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2026\/05\/CC-PT-07-26-FULL-TIME-RATES-05.2026.pdf\">CC PT 07-26 FULL TIME RATES 05.2026<\/a>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un mensaje de DSS &#8211; Programa de Cuidado y Desarrollo Infantil: A partir del 1 de junio de 2026, cuando&#8230;<\/p>\n","protected":false},"author":2,"featured_media":18516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[72],"tags":[],"class_list":["post-18576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dss-programa-de-cuidado-infantil-y-desarrollo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tasas de reembolso a tiempo completo - The Nevada Registry<\/title>\n<meta name=\"description\" content=\"Un mensaje de DSS - Programa de Cuidado y Desarrollo Infantil: A partir del 1 de junio de 2026, cuando un ni\u00f1o asista durante quince (15) minutos o m\u00e1s en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tasas de reembolso a tiempo completo - The Nevada Registry\" \/>\n<meta property=\"og:description\" content=\"Un mensaje de DSS - Programa de Cuidado y Desarrollo Infantil: A partir del 1 de junio de 2026, cuando un ni\u00f1o asista durante quince (15) minutos o m\u00e1s en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/\" \/>\n<meta property=\"og:site_name\" content=\"The Nevada Registry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nevadaregistry\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-21T21:37:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T21:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2026\/04\/ccdp-logo-002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"588\" \/>\n\t<meta property=\"og:image:height\" content=\"347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shelly Nye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shelly Nye\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/\"},\"author\":{\"name\":\"Shelly Nye\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\"},\"headline\":\"Tasas de reembolso a tiempo completo\",\"datePublished\":\"2026-05-21T21:37:40+00:00\",\"dateModified\":\"2026-05-21T21:38:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/\"},\"wordCount\":123,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ccdp-logo-002.jpg\",\"articleSection\":[\"DSS - Programa de Cuidado Infantil y Desarrollo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/\",\"name\":\"Tasas de reembolso a tiempo completo - The Nevada Registry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ccdp-logo-002.jpg\",\"datePublished\":\"2026-05-21T21:37:40+00:00\",\"dateModified\":\"2026-05-21T21:38:11+00:00\",\"description\":\"Un mensaje de DSS - Programa de Cuidado y Desarrollo Infantil: A partir del 1 de junio de 2026, cuando un ni\u00f1o asista durante quince (15) minutos o m\u00e1s en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ccdp-logo-002.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ccdp-logo-002.jpg\",\"width\":\"588\",\"height\":\"347\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/news-updates\\\/tasas-de-reembolso-a-tiempo-completo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/pagina-principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tasas de reembolso a tiempo completo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"name\":\"The Nevada Registry\",\"description\":\"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#organization\",\"name\":\"El Nevada Registry\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nevadaregistry.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/tnr-logo-purple-copy.jpg\",\"width\":\"900\",\"height\":\"562\",\"caption\":\"El Nevada Registry\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nevadaregistry\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nevadaregistry.org\\\/es\\\/#\\\/schema\\\/person\\\/1bad6d3bd100b050a3a293469ef79985\",\"name\":\"Shelly Nye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g\",\"caption\":\"Shelly Nye\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tasas de reembolso a tiempo completo - The Nevada Registry","description":"Un mensaje de DSS - Programa de Cuidado y Desarrollo Infantil: A partir del 1 de junio de 2026, cuando un ni\u00f1o asista durante quince (15) minutos o m\u00e1s en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/","og_locale":"es_ES","og_type":"article","og_title":"Tasas de reembolso a tiempo completo - The Nevada Registry","og_description":"Un mensaje de DSS - Programa de Cuidado y Desarrollo Infantil: A partir del 1 de junio de 2026, cuando un ni\u00f1o asista durante quince (15) minutos o m\u00e1s en","og_url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/","og_site_name":"The Nevada Registry","article_publisher":"https:\/\/www.facebook.com\/nevadaregistry","article_published_time":"2026-05-21T21:37:40+00:00","article_modified_time":"2026-05-21T21:38:11+00:00","og_image":[{"width":588,"height":347,"url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2026\/04\/ccdp-logo-002.jpg","type":"image\/jpeg"}],"author":"Shelly Nye","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Shelly Nye","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/#article","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/"},"author":{"name":"Shelly Nye","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985"},"headline":"Tasas de reembolso a tiempo completo","datePublished":"2026-05-21T21:37:40+00:00","dateModified":"2026-05-21T21:38:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/"},"wordCount":123,"publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2026\/04\/ccdp-logo-002.jpg","articleSection":["DSS - Programa de Cuidado Infantil y Desarrollo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/","url":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/","name":"Tasas de reembolso a tiempo completo - The Nevada Registry","isPartOf":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/#primaryimage"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2026\/04\/ccdp-logo-002.jpg","datePublished":"2026-05-21T21:37:40+00:00","dateModified":"2026-05-21T21:38:11+00:00","description":"Un mensaje de DSS - Programa de Cuidado y Desarrollo Infantil: A partir del 1 de junio de 2026, cuando un ni\u00f1o asista durante quince (15) minutos o m\u00e1s en","breadcrumb":{"@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/#primaryimage","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2026\/04\/ccdp-logo-002.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2026\/04\/ccdp-logo-002.jpg","width":"588","height":"347"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nevadaregistry.org\/es\/news-updates\/tasas-de-reembolso-a-tiempo-completo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nevadaregistry.org\/es\/pagina-principal\/"},{"@type":"ListItem","position":2,"name":"Tasas de reembolso a tiempo completo"}]},{"@type":"WebSite","@id":"https:\/\/www.nevadaregistry.org\/es\/#website","url":"https:\/\/www.nevadaregistry.org\/es\/","name":"The Nevada Registry","description":"Workforce data system capturing information about the Early Childhood Education and Care (ECEC) workforce in Nevada.","publisher":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nevadaregistry.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nevadaregistry.org\/es\/#organization","name":"El Nevada Registry","url":"https:\/\/www.nevadaregistry.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","contentUrl":"https:\/\/www.nevadaregistry.org\/wp-content\/uploads\/2020\/10\/tnr-logo-purple-copy.jpg","width":"900","height":"562","caption":"El Nevada Registry"},"image":{"@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nevadaregistry"]},{"@type":"Person","@id":"https:\/\/www.nevadaregistry.org\/es\/#\/schema\/person\/1bad6d3bd100b050a3a293469ef79985","name":"Shelly Nye","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/837d4ba871ac094534f3f9258d55ce0296384282b42745091ee4e3cc5c854046?s=96&d=mm&r=g","caption":"Shelly Nye"}}]}},"_links":{"self":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/18576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/comments?post=18576"}],"version-history":[{"count":1,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/18576\/revisions"}],"predecessor-version":[{"id":18578,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/posts\/18576\/revisions\/18578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media\/18516"}],"wp:attachment":[{"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/media?parent=18576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/categories?post=18576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nevadaregistry.org\/es\/wp-json\/wp\/v2\/tags?post=18576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}